{"id":3614,"date":"2020-09-24T19:58:02","date_gmt":"2020-09-24T17:58:02","guid":{"rendered":"https:\/\/www.viajarsolo.com\/blog\/?p=3614"},"modified":"2020-09-25T11:38:11","modified_gmt":"2020-09-25T09:38:11","slug":"viaja-con-nosotros-este-otono","status":"publish","type":"post","link":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/","title":{"rendered":"Viaja con nosotros este oto\u00f1o"},"content":{"rendered":"<p>Aunque todav\u00eda no tenemos la movilidad que nos gustar\u00eda, este verano han sido muchos los viajeros que se han animado a visitar Espa\u00f1a con nosotros. Nos aseguramos que en todos nuestros viajes <strong>se cumplan todas las medidas sanitarias recomendadas<\/strong> y, por eso, con este art\u00edculo queremos animarte y decirte: \u00a1Viaja con nosotros este oto\u00f1o!<\/p>\n<p>Te vamos a hablar de cuatro viajes que no te puedes perder y te adelantamos que, para invierno, estamos preparando un viaje al que no te podr\u00e1s resistir. As\u00ed que, sigue leyendo para enterarte de todo lo que vas a poder disfrutar.<\/p>\n<p><!--more-->Cuando llega oto\u00f1o solemos pensar que se ha pasado el mejor tiempo para viajar, pero eso no es as\u00ed. En nuestro blog tenemos varios art\u00edculos que puedes leer o releer en los que explicamos las ventajas de <strong>viajar en oto\u00f1o<\/strong>. Te los dejamos aqu\u00ed por si te interesan: <a href=\"https:\/\/www.viajarsolo.com\/blog\/otono-una-epoca-ideal-para-viajar\/#more-2813\" target=\"_blank\" rel=\"noopener noreferrer\">Oto\u00f1o, una \u00e9poca ideal para viajar<\/a>\u00a0y tambi\u00e9n <a href=\"https:\/\/www.viajarsolo.com\/blog\/cuando-viajar-verano-otono\/#more-3177\" target=\"_blank\" rel=\"noopener noreferrer\">Cuando Viajar \u00bfen Verano o en Oto\u00f1o?<\/a>.<\/p>\n<p>Es verdad que algunos de los sitios de los que hablamos en estos art\u00edculos este a\u00f1o no est\u00e1n disponibles, pero tenemos muchos que si y otros nuevos.<\/p>\n<h2>Valdepe\u00f1as, vinos y bodegas Single<\/h2>\n<p>Empezamos por un viaje de tan solo tres d\u00edas en el que combinamos la <strong>enolog\u00eda<\/strong>, la <strong>cultura<\/strong> y la <strong>gastronom\u00eda<\/strong>: viaja con nosotros este oto\u00f1o a Castilla-La Mancha con nuestro viaje <a href=\"https:\/\/www.viajarsolo.com\/valdepenas-vinos-y-bodegas-single-viajar-solo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Valdepe\u00f1as, vinos y bodegas Single<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3621\" src=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-300x94.jpg\" alt=\"\" width=\"1920\" height=\"600\" srcset=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-300x94.jpg 300w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-1024x320.jpg 1024w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-768x240.jpg 768w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-1536x480.jpg 1536w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo-617x193.jpg 617w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/uva-vid-vinedo.jpg 1920w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En esta escapada Single te llevaremos a <strong>Valdepe\u00f1as<\/strong> para visitar un vi\u00f1edo y una bodega singular. All\u00ed, adem\u00e1s de conocer todo lo relacionado con la elaboraci\u00f3n del vino, haremos una comida campera. Por supuesto, conoceremos los monumentos y museos de esta ciudad famosa por sus caldos. Y, a\u00fan tendremos tiempo de disfrutar de la buena gastronom\u00eda y la zona de copas.<\/p>\n<p>Un fin de semana intenso y muy bien aprovechado. Para conocer a gente que viaja sola y que tiene ganas de divertirse y desconectar.<\/p>\n<h2>Relax y Bienestar en C\u00e1diz<\/h2>\n<p>Este viaje que te ayudar\u00e1 a sentirte mejor a trav\u00e9s del <strong>autocuidado y del acercamiento a la naturaleza<\/strong>: viaja con nosotros este oto\u00f1o al sur de la pen\u00ednsula con nuestro viaje <a href=\"https:\/\/www.viajarsolo.com\/relax-y-bienestar-en-cadiz-viajar-solo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Relax y Bienestar en C\u00e1diz<\/a>.<\/p>\n<p>En un entorno \u00fanico y con pensi\u00f3n completa, te ayudaremos a redescubrir y recordar la capacidad que tenemos para cuidarnos, a trav\u00e9s de t\u00e9cnicas de <strong>yoga<\/strong>, <strong>automasajes<\/strong> y el acercamiento a la naturaleza. Adem\u00e1s tendr\u00e1s recursos para que, cuando vuelvas a la vida cotidiana, seas capaz de recobrar todo la <strong>calma y felicidad<\/strong> que habr\u00e1s alcanzado aqu\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mujer-yoga-naturaleza-espaldas-e1600966877663.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3616\" src=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mujer-yoga-naturaleza-espaldas-e1600966877663-300x94.jpg\" alt=\"Relax y Bienstar en C\u00e1diz\" width=\"1200\" height=\"600\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Es uno de los viajes nuevos y ha sido todo un \u00e9xito. S\u00f3lo tienes que pasarte por la p\u00e1gina para leer los comentarios de los viajeros de agosto. Aprovecha el <strong>puente de octubre<\/strong> para disfrutar de estos 4 d\u00edas inolvidables.<\/p>\n<h2>Verano single en Costa Azahar<\/h2>\n<p>Alarga el verano con esta salida de 4 d\u00edas para el puente de octubre. Viaja con nosotros este oto\u00f1o a <strong>Castell\u00f3n<\/strong> con nuestro viaje <a href=\"https:\/\/www.viajarsolo.com\/verano-single-en-costa-azahar-viajar-solo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Verano single en Costa Azahar<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignventer size-full wp-image-3629\" src=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-300x94.jpg\" alt=\"Velero Jorge dxt\" width=\"1920\" height=\"600\" srcset=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-300x94.jpg 300w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-1024x320.jpg 1024w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-768x240.jpg 768w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-1536x480.jpg 1536w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge-617x193.jpg 617w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/velero-dxt-jorge.jpg 1920w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Un viaje exclusivo de ViajarSolo en el que se combina la <strong>navegaci\u00f3n en velero<\/strong> con la buena gastronom\u00eda de la zona y un fant\u00e1stico paseo en <strong>bicicleta<\/strong>. Sin olvidarnos de la diversi\u00f3n en las maravillosas noches de Benicassim. \u00a1Incluso iremos a un spa!<\/p>\n<p>Tanto si eres single, como si, por las circunstancias, tienes que viajar s\u00f3lo, esta salida te ofrece <strong>diversi\u00f3n<\/strong> y actividades al lado del mar para ayudarte a <strong>desconectar<\/strong> y volver totalmente renovado.<\/p>\n<h2>Mar y monta\u00f1a<\/h2>\n<p>Un viaje para estar en contacto con la naturaleza y descubrir la Tarragona desconocida. Viaja con nosotros este oto\u00f1o al <a href=\"https:\/\/www.viajarsolo.com\/caminando-montana-y-mar-viajar-solo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mar y monta\u00f1a<\/a> de las tierras del Ebro.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3627\" src=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-300x94.jpg\" alt=\"Puesta de sol en el Delta del Ebro\" width=\"1920\" height=\"600\" srcset=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-300x94.jpg 300w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-1024x320.jpg 1024w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-768x240.jpg 768w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-1536x480.jpg 1536w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol-617x193.jpg 617w, https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/mar-y-montana-delta-ebro-puesta-sol.jpg 1920w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En este viaje tenemos varias salidas en las que descubriremos muchos paisajes diferentes. Recorreremos el <strong>Delta del Ebro<\/strong> y su vida tradicional. Visitaremos el Parque Natural de Els Ports para disfrutar de la <strong>tranquilidad<\/strong> de sus monta\u00f1as y r\u00edos. Y caminaremos por prados y <strong>bosques<\/strong> a m\u00e1s de 1.000 m de altura llegando a un impresionante mirador.<\/p>\n<p>Un viaje de 5 d\u00edas para <strong>oxigenarnos<\/strong> y disfrutar de unos paisajes espectaculares.<\/p>\n<p>Y, para terminar os contamos que, para <strong>diciembre<\/strong>, tenemos un viaje incre\u00edble, un viaje a <strong>Maldivas<\/strong>. Este es uno de los pocos destinos fuera de Espa\u00f1a a los que se puede <strong>viajar con seguridad<\/strong>. Pod\u00e9is verlo ya en nuestra web o esperar un poco a que escribamos un art\u00edculo sobre \u00e9l.<\/p>\n<p>\u00a1Estad atentos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque todav\u00eda no tenemos la movilidad que nos gustar\u00eda, este verano han sido muchos los viajeros que se han animado a visitar Espa\u00f1a con nosotros. Nos aseguramos que en todos nuestros viajes se cumplan todas las medidas sanitarias recomendadas y, por eso, con este art\u00edculo queremos animarte y decirte: \u00a1Viaja con nosotros este oto\u00f1o! Te [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":3642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[128,130,357,302],"tags":[360,96,117,118,142,214],"class_list":["post-3614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naturaleza","category-viajes-de-relax","category-viajes-por-espana","category-viajes-singles","tag-oto","tag-singles","tag-viajarsolo","tag-viaje","tag-viaje-single","tag-viajes-singles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viaja con nosotros este oto\u00f1o - ViajarSolo Blog<\/title>\n<meta name=\"description\" content=\"Si en verano no has podido viajar, te recordamos que nuestros viajes cumplen con las medidas sanitarias recomendadas \u00a1Viaja con nosotros este oto\u00f1o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viaja con nosotros este oto\u00f1o - ViajarSolo Blog\" \/>\n<meta property=\"og:description\" content=\"Si en verano no has podido viajar, te recordamos que nuestros viajes cumplen con las medidas sanitarias recomendadas \u00a1Viaja con nosotros este oto\u00f1o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/\" \/>\n<meta property=\"og:site_name\" content=\"ViajarSolo Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ViajarSolo\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T17:58:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-25T09:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raquel Peir\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ViajarSolo\" \/>\n<meta name=\"twitter:site\" content=\"@ViajarSolo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel Peir\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viaja con nosotros este oto\u00f1o - ViajarSolo Blog","description":"Si en verano no has podido viajar, te recordamos que nuestros viajes cumplen con las medidas sanitarias recomendadas \u00a1Viaja con nosotros este oto\u00f1o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/","og_locale":"es_ES","og_type":"article","og_title":"Viaja con nosotros este oto\u00f1o - ViajarSolo Blog","og_description":"Si en verano no has podido viajar, te recordamos que nuestros viajes cumplen con las medidas sanitarias recomendadas \u00a1Viaja con nosotros este oto\u00f1o!","og_url":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/","og_site_name":"ViajarSolo Blog","article_publisher":"https:\/\/www.facebook.com\/ViajarSolo","article_published_time":"2020-09-24T17:58:02+00:00","article_modified_time":"2020-09-25T09:38:11+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg","type":"image\/jpeg"}],"author":"Raquel Peir\u00f3","twitter_card":"summary_large_image","twitter_creator":"@ViajarSolo","twitter_site":"@ViajarSolo","twitter_misc":{"Escrito por":"Raquel Peir\u00f3","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#article","isPartOf":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/"},"author":{"name":"Raquel Peir\u00f3","@id":"https:\/\/www.viajarsolo.com\/blog\/#\/schema\/person\/1b435b37591af33fffdf9b4b02394c2c"},"headline":"Viaja con nosotros este oto\u00f1o","datePublished":"2020-09-24T17:58:02+00:00","dateModified":"2020-09-25T09:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/"},"wordCount":784,"commentCount":0,"publisher":{"@id":"https:\/\/www.viajarsolo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg","keywords":["oto","Singles","viajarsolo","viaje","viaje single","Viajes singles"],"articleSection":["Naturaleza","Viajes de Relax","Viajes por Espa\u00f1a","Viajes Singles"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/","url":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/","name":"Viaja con nosotros este oto\u00f1o - ViajarSolo Blog","isPartOf":{"@id":"https:\/\/www.viajarsolo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#primaryimage"},"image":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg","datePublished":"2020-09-24T17:58:02+00:00","dateModified":"2020-09-25T09:38:11+00:00","description":"Si en verano no has podido viajar, te recordamos que nuestros viajes cumplen con las medidas sanitarias recomendadas \u00a1Viaja con nosotros este oto\u00f1o!","breadcrumb":{"@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#primaryimage","url":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg","contentUrl":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2020\/09\/carretera-otono.jpg","width":1920,"height":600,"caption":"viajar en oto\u00f1o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viajarsolo.com\/blog\/viaja-con-nosotros-este-otono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.viajarsolo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Viaja con nosotros este oto\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.viajarsolo.com\/blog\/#website","url":"https:\/\/www.viajarsolo.com\/blog\/","name":"ViajarSolo Blog","description":"Punto de encuentro de los que tienen la pasi\u00f3n por viajar","publisher":{"@id":"https:\/\/www.viajarsolo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viajarsolo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.viajarsolo.com\/blog\/#organization","name":"ViajarSolo","url":"https:\/\/www.viajarsolo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.viajarsolo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2023\/07\/buzon7x2_0.jpg","contentUrl":"https:\/\/www.viajarsolo.com\/blog\/wp-content\/uploads\/2023\/07\/buzon7x2_0.jpg","width":874,"height":283,"caption":"ViajarSolo"},"image":{"@id":"https:\/\/www.viajarsolo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ViajarSolo","https:\/\/x.com\/ViajarSolo","https:\/\/www.instagram.com\/viajarsolo\/"]},{"@type":"Person","@id":"https:\/\/www.viajarsolo.com\/blog\/#\/schema\/person\/1b435b37591af33fffdf9b4b02394c2c","name":"Raquel Peir\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44febc1f0bd284b982da56e0040ae2505e0179f31ce09e0cc3a3f7e83994a2d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44febc1f0bd284b982da56e0040ae2505e0179f31ce09e0cc3a3f7e83994a2d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44febc1f0bd284b982da56e0040ae2505e0179f31ce09e0cc3a3f7e83994a2d9?s=96&d=mm&r=g","caption":"Raquel Peir\u00f3"}}]}},"_links":{"self":[{"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/posts\/3614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/comments?post=3614"}],"version-history":[{"count":0,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/posts\/3614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/media\/3642"}],"wp:attachment":[{"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/media?parent=3614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/categories?post=3614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viajarsolo.com\/blog\/wp-json\/wp\/v2\/tags?post=3614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}